{"id":5750,"date":"2024-12-13T19:40:23","date_gmt":"2024-12-13T19:40:23","guid":{"rendered":"https:\/\/fussball-in-irland.eu\/?p=5750"},"modified":"2025-12-19T20:06:44","modified_gmt":"2025-12-19T20:06:44","slug":"dritte-liga-ab-2026","status":"publish","type":"post","link":"https:\/\/fussball-in-irland.eu\/index.php\/2024\/12\/13\/dritte-liga-ab-2026\/","title":{"rendered":"Dritte Liga ab 2026?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Es ist schon etwas her, dass ich hier mal <a href=\"https:\/\/fussball-in-irland.eu\/index.php\/2022\/07\/23\/dritte-liga-fruehestens-2024\/\" data-type=\"post\" data-id=\"4166\">\u00fcber Pl\u00e4ne f\u00fcr eine dritte Liga in Irland geschrieben<\/a> habe. Jetzt gibt es aber Neuigkeiten zum Thema: Die Pl\u00e4ne scheinen konkreter zu werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber der Reihe nach: Es gab schon einmal eine dritte Liga in Irland, die sogenannte &#8222;A Championship&#8220;, die von 2008 bis 2011 lief, also relativ kurz und m\u00e4\u00dfig erfolgreich. Ende 2021 h\u00f6rte man dann zum ersten Mal, dass es \u00dcberlegungen zu einer neuen dritten Liga gibt. Im Februar 2022 tauchte die dritte Liga dann in einem Strategiepapier der FAI auf, mit dem ambitionierten Ziel, sie schon 2023 einzuf\u00fchren. Ein halbes Jahr sp\u00e4ter hatte man dann gemerkt, dass das wohl zu ambitioniert war, und hat den Starttermin auf fr\u00fchestens 2024 verschoben. Nun ja, 2024 ist jetzt schon fast vorbei, und die dritte Liga gibt es immer noch nicht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dass ich das Thema jetzt aufgreife, h\u00e4ngt damit zusammen, dass die FAI nun einen (vorl\u00e4ufigen?) Plan zu haben scheint und <a href=\"https:\/\/www.fai.ie\/latest\/fai-welcomes-expressions-interest-new-national-league\/\">Vereine einl\u00e4dt, ihr Interesse an einer Teilnahme ab 2026 anzumelden<\/a>. Der Plan sieht offenbar vor, eine &#8222;National League&#8220; genannte dritte Liga mit zwei Staffeln (Nord und S\u00fcd) und je 10 Mannschaften pro Staffel einzuf\u00fchren. Gestartet werden soll 2026 mit einer Kurzsaison ab August und 2027 mit der ersten vollen Saison. Es soll die M\u00f6glichkeit von Auf- und Abstieg zwischen der First Division und der National League geben, und die Mannschaften in der National League w\u00e4ren auch f\u00fcr die Teilnahme am FAI Cup qualifiziert. Das Ganze ist offenbar ein Baustein im langfristigen Plan der FAI, die sehr fragmentierte Fussball-Landschaft in Irland zu einer funktionierenden Pyramide zusammenzuf\u00fchren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vereine haben jetzt bis 21. Februar 2025 Zeit, ihr Interesse an einer Teilnahme an der National League zu anzumelden. Relativ kurz, wie ich finde, aber mal abwarten, was sich ergibt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es ist schon etwas her, dass ich hier mal \u00fcber Pl\u00e4ne f\u00fcr eine dritte Liga in Irland geschrieben habe. Jetzt gibt es aber Neuigkeiten zum Thema: Die Pl\u00e4ne scheinen konkreter zu werden. Aber der Reihe nach: Es gab schon einmal eine dritte Liga in Irland, die sogenannte &#8222;A Championship&#8220;, die von 2008 bis 2011 lief, &hellip; <a href=\"https:\/\/fussball-in-irland.eu\/index.php\/2024\/12\/13\/dritte-liga-ab-2026\/\" class=\"more-link\"><span class=\"screen-reader-text\">Dritte Liga ab 2026?<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,4,18],"tags":[],"class_list":["post-5750","post","type-post","status-publish","format-standard","hentry","category-fai","category-league-of-ireland","category-national-league"],"_links":{"self":[{"href":"https:\/\/fussball-in-irland.eu\/index.php\/wp-json\/wp\/v2\/posts\/5750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fussball-in-irland.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fussball-in-irland.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fussball-in-irland.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fussball-in-irland.eu\/index.php\/wp-json\/wp\/v2\/comments?post=5750"}],"version-history":[{"count":1,"href":"https:\/\/fussball-in-irland.eu\/index.php\/wp-json\/wp\/v2\/posts\/5750\/revisions"}],"predecessor-version":[{"id":5751,"href":"https:\/\/fussball-in-irland.eu\/index.php\/wp-json\/wp\/v2\/posts\/5750\/revisions\/5751"}],"wp:attachment":[{"href":"https:\/\/fussball-in-irland.eu\/index.php\/wp-json\/wp\/v2\/media?parent=5750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fussball-in-irland.eu\/index.php\/wp-json\/wp\/v2\/categories?post=5750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fussball-in-irland.eu\/index.php\/wp-json\/wp\/v2\/tags?post=5750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}